{"id":1579,"date":"2015-07-24T14:55:45","date_gmt":"2015-07-24T12:55:45","guid":{"rendered":"http:\/\/www.homemaison.com\/blog\/?p=1579"},"modified":"2026-05-28T14:20:34","modified_gmt":"2026-05-28T13:20:34","slug":"home-maison-le-sur-mesure","status":"publish","type":"post","link":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/","title":{"rendered":"Home Maison &#038; le sur-mesure"},"content":{"rendered":"<p>De nos jours de plus en plus de produits ne sont plus dans les \u00ab\u00a0normes\u00a0\u00bb. Les normes changent et c\u2019est pourquoi Home Maison cherche \u00e0 satisfaire le maximum de clients en am\u00e9liorant et en augmentant sa gamme de produits confectionn\u00e9s sur-mesure.<\/p>\n<p style=\"text-align: left;\">HomeMaison, petite entreprise familiale au centre de la France, est le sp\u00e9cialiste du rideau et voilage depuis 2006. En plus du <a href=\"https:\/\/www.homemaison.com\/fr\/27-rideaux\">rideau pr\u00eat \u00e0 poser<\/a> aux dimensions standards, nous allons plus loin en offrant la possibilit\u00e9 de personnaliser votre rideau \u00e0 l\u2019aide de notre configurateur sur mesure. Vous souhaitez des dimensions particuli\u00e8res ? Une finition de t\u00eate correspondant au style de votre d\u00e9coration ? O\u00f9 vous souhaitez simplement cr\u00e9er un rideau thermique ? Vous concevez, nous confectionnons !<\/p>\n<h2><a href=\"https:\/\/www.homemaison.com\/fr\/27-19-rideaux-rideaux-sur-mesure\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8068 size-large\" src=\"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/voilage-sur-mesure-600x300.jpg\" alt=\"voilage fluide en lin\" width=\"600\" height=\"300\" srcset=\"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/voilage-sur-mesure-600x300.jpg 600w, https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/voilage-sur-mesure-300x150.jpg 300w, https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/voilage-sur-mesure-768x384.jpg 768w, https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/voilage-sur-mesure-120x60.jpg 120w, https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/voilage-sur-mesure.jpg 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/h2>\n<h2 style=\"text-align: center;\">Comment cr\u00e9er son rideau sur mesure ?<\/h2>\n<p>En seulement quelques clics,\u00a0 cr\u00e9ez votre rideau ou <a href=\"https:\/\/www.homemaison.com\/fr\/80-22-voilages-voilages-sur-mesure\">voilage sur mesure<\/a> :<\/p>\n<ol style=\"text-align: left;\">\n<li>Mon coloris<\/li>\n<li>La dimension du rideau<\/li>\n<li>Ma t\u00eate de rideau<\/li>\n<li>Ma doublure<\/li>\n<li>Mes accessoires<\/li>\n<li>La quantit\u00e9<\/li>\n<\/ol>\n<p style=\"text-align: left;\">Une fois\u00a0la commande valid\u00e9e, votre projet est pris en charge par notre atelier de confection fran\u00e7ais dans nos locaux situ\u00e9 pr\u00e8s de Lyon et est exp\u00e9di\u00e9e sous 10 jours ouvr\u00e9s. Nous assurons une exp\u00e9dition soign\u00e9e, une confection 100% made in France de vos commandes sur-mesure et une r\u00e9ception rapide, ainsi qu&rsquo;un service client \u00e0 votre \u00e9coute.<br \/>\nEn conclusion, c\u2019est un savoir-faire de qualit\u00e9 et des services vari\u00e9s que nous vous proposons.<\/p>\n<p><a href=\"https:\/\/www.homemaison.com\/fr\/27-19-rideaux-rideaux-sur-mesure\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-8062 aligncenter\" src=\"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/FINITIONS-DE-TETE-600x450.jpg\" alt=\"rideau sur mesure avec diff\u00e9rentes t\u00eate de rideau\" width=\"600\" height=\"450\" srcset=\"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/FINITIONS-DE-TETE-600x450.jpg 600w, https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/FINITIONS-DE-TETE-300x225.jpg 300w, https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/FINITIONS-DE-TETE-768x576.jpg 768w, https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/FINITIONS-DE-TETE-1536x1152.jpg 1536w, https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/FINITIONS-DE-TETE-80x60.jpg 80w, https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/FINITIONS-DE-TETE.jpg 2000w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<h2 style=\"text-align: center;\">HomeMaison, sp\u00e9cialiste du sur mesure<\/h2>\n<p style=\"text-align: left;\">D\u00e9couvrez l\u2019ensemble des cat\u00e9gories proposant le \u00ab\u00a0sur-mesure\u00a0\u00bb de Home maison\u00a0:<\/p>\n<p style=\"text-align: left;\">&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Rideaux sur-mesure\u00a0:<br \/>\nDans un premier temps, confectionnez votre rideau en choisissant la mati\u00e8re parmi de nombreux tissus (velours, coton, lin, polyester, jacquard\u2026), ses dimensions en fonction du rendu que vous souhaitez (tomb\u00e9 net, tomb\u00e9 rasant ou tomb\u00e9 cassant), et ses finitions comme oeillet, passants cach\u00e9s, ourlet passe-tringle, passants visible, nouettes, fronce avec anneaux, galon fronceur sur rail, pliss\u00e9 vague, plis flamand ou bande velcro. Pour finir, vous pouvez ajouter une doublure occultante noir, une doublure occultante blanche ou une doublure occultante + isolante \u00e9cru et \u00e9galement avec ou sans embrasse.<br \/>\nAinsi votre rideau sera personnalis\u00e9 \u00e0 vos go\u00fbts et au style de votre int\u00e9rieur.<\/p>\n<p style=\"text-align: left;\">&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Voilage sur-mesure\u00a0:<br \/>\nConfectionnez \u00a0votre voilage sur-mesure selon vos go\u00fbts en choisissant votre tissu, vos dimensions, et vos finitions. Profitez d\u2019un large choix en termes de mati\u00e8re, de couleurs, de motifs, unis, \u00e0 rayures, \u00e0 imprim\u00e9s.<\/p>\n<p style=\"text-align: left;\">&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Tringle sur-mesure\u00a0:<br \/>\nSelon le mod\u00e8le de tringle la longueur est comprise entre 60 cm et 800 cm, et son diam\u00e8tre entre 16 et 28 mm.<br \/>\nCette gamme est vari\u00e9 de par la diversit\u00e9 des mati\u00e8res telles que le m\u00e9tal, le fer, le bois\u2026 et de par la diversit\u00e9 des coloris tels que dor\u00e9, chrom\u00e9, nickel, mat, brillant\u2026<\/p>\n<p>Envie d&rsquo;en savoir plus ? D\u00e9couvrez l&rsquo;article <a href=\"https:\/\/www.homemaison.com\/blog\/comment-confectionner-son-rideau-sur-mesure-en-5-etapes\/\">Confectionner son rideau sur mesure en 6 \u00e9tapes.<\/a><\/p>\n<p><a href=\"https:\/\/www.homemaison.com\/fr\/\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-8064 aligncenter\" src=\"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure-600x300.jpg\" alt=\"rideau sur mesure voilage sur mesure\" width=\"600\" height=\"300\" srcset=\"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure-600x300.jpg 600w, https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure-300x150.jpg 300w, https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure-768x384.jpg 768w, https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure-120x60.jpg 120w, https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure.jpg 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De nos jours de plus en plus de produits ne sont plus dans les \u00ab\u00a0normes\u00a0\u00bb. Les normes changent et c\u2019est pourquoi Home Maison cherche \u00e0 satisfaire le maximum de clients en am\u00e9liorant et en augmentant sa gamme de produits confectionn\u00e9s sur-mesure. HomeMaison, petite entreprise familiale au centre de la France, est le sp\u00e9cialiste du rideau &hellip; <\/p>\n","protected":false},"author":1,"featured_media":8064,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[2],"tags":[540,541,544,627,626,561,628],"class_list":["post-1579","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tous-nos-articles","tag-home-maison","tag-homemaison","tag-rideau","tag-rideau-sur-mesure","tag-sur-mesure","tag-voilage","tag-voilage-sur-mesure","latest_post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Home Maison &amp; le sur-mesure - Le blog d\u00e9co HomeMaison<\/title>\n<meta name=\"description\" content=\"HomeMaison propose un service sur mesure pour les rideaux, les voilages et les tringles : mati\u00e8re, dimensions, finition - HomeMaison\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home Maison &amp; le sur-mesure - Le blog d\u00e9co HomeMaison\" \/>\n<meta property=\"og:description\" content=\"HomeMaison propose un service sur mesure pour les rideaux, les voilages et les tringles : mati\u00e8re, dimensions, finition - HomeMaison\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/\" \/>\n<meta property=\"og:site_name\" content=\"Le blog d\u00e9co HomeMaison\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/homemaison\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-24T12:55:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T13:20:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Home Maison\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@homemaison\" \/>\n<meta name=\"twitter:site\" content=\"@homemaison\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Home Maison\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/\"},\"author\":{\"name\":\"Home Maison\",\"@id\":\"https:\/\/www.homemaison.com\/blog\/#\/schema\/person\/95d44530486a00dc07b82cadbf7bb295\"},\"headline\":\"Home Maison &#038; le sur-mesure\",\"datePublished\":\"2015-07-24T12:55:45+00:00\",\"dateModified\":\"2026-05-28T13:20:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/\"},\"wordCount\":477,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.homemaison.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure.jpg\",\"keywords\":[\"home maison\",\"homemaison\",\"rideau\",\"rideau sur mesure\",\"sur mesure\",\"voilage\",\"voilage sur mesure\"],\"articleSection\":[\"Tous nos articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/\",\"url\":\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/\",\"name\":\"Home Maison & le sur-mesure - Le blog d\u00e9co HomeMaison\",\"isPartOf\":{\"@id\":\"https:\/\/www.homemaison.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure.jpg\",\"datePublished\":\"2015-07-24T12:55:45+00:00\",\"dateModified\":\"2026-05-28T13:20:34+00:00\",\"description\":\"HomeMaison propose un service sur mesure pour les rideaux, les voilages et les tringles : mati\u00e8re, dimensions, finition - HomeMaison\",\"breadcrumb\":{\"@id\":\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#primaryimage\",\"url\":\"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure.jpg\",\"contentUrl\":\"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure.jpg\",\"width\":800,\"height\":400,\"caption\":\"rideau sur mesure voilage sur mesure\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Tous nos articles\",\"item\":\"https:\/\/www.homemaison.com\/blog\/category\/tous-nos-articles\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home Maison &#038; le sur-mesure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.homemaison.com\/blog\/#website\",\"url\":\"https:\/\/www.homemaison.com\/blog\/\",\"name\":\"Le blog d\u00e9co HomeMaison\",\"description\":\"Un blog qui se veut inspirant\",\"publisher\":{\"@id\":\"https:\/\/www.homemaison.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.homemaison.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.homemaison.com\/blog\/#organization\",\"name\":\"Home Maison\",\"url\":\"https:\/\/www.homemaison.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.homemaison.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2021\/03\/cropped-blog-logo-HM-1.png\",\"contentUrl\":\"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2021\/03\/cropped-blog-logo-HM-1.png\",\"width\":400,\"height\":138,\"caption\":\"Home Maison\"},\"image\":{\"@id\":\"https:\/\/www.homemaison.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/homemaison\",\"https:\/\/x.com\/homemaison\",\"https:\/\/www.instagram.com\/homemaison\/\",\"https:\/\/fr.pinterest.com\/homemaison\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.homemaison.com\/blog\/#\/schema\/person\/95d44530486a00dc07b82cadbf7bb295\",\"name\":\"Home Maison\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.homemaison.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3e8f4e2a391b3c2f7cef6f6a9c683bb1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3e8f4e2a391b3c2f7cef6f6a9c683bb1?s=96&d=mm&r=g\",\"caption\":\"Home Maison\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home Maison & le sur-mesure - Le blog d\u00e9co HomeMaison","description":"HomeMaison propose un service sur mesure pour les rideaux, les voilages et les tringles : mati\u00e8re, dimensions, finition - HomeMaison","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/","og_locale":"fr_FR","og_type":"article","og_title":"Home Maison & le sur-mesure - Le blog d\u00e9co HomeMaison","og_description":"HomeMaison propose un service sur mesure pour les rideaux, les voilages et les tringles : mati\u00e8re, dimensions, finition - HomeMaison","og_url":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/","og_site_name":"Le blog d\u00e9co HomeMaison","article_publisher":"https:\/\/www.facebook.com\/homemaison","article_published_time":"2015-07-24T12:55:45+00:00","article_modified_time":"2026-05-28T13:20:34+00:00","og_image":[{"width":800,"height":400,"url":"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure.jpg","type":"image\/jpeg"}],"author":"Home Maison","twitter_card":"summary_large_image","twitter_creator":"@homemaison","twitter_site":"@homemaison","twitter_misc":{"\u00c9crit par":"Home Maison","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#article","isPartOf":{"@id":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/"},"author":{"name":"Home Maison","@id":"https:\/\/www.homemaison.com\/blog\/#\/schema\/person\/95d44530486a00dc07b82cadbf7bb295"},"headline":"Home Maison &#038; le sur-mesure","datePublished":"2015-07-24T12:55:45+00:00","dateModified":"2026-05-28T13:20:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/"},"wordCount":477,"commentCount":1,"publisher":{"@id":"https:\/\/www.homemaison.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#primaryimage"},"thumbnailUrl":"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure.jpg","keywords":["home maison","homemaison","rideau","rideau sur mesure","sur mesure","voilage","voilage sur mesure"],"articleSection":["Tous nos articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/","url":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/","name":"Home Maison & le sur-mesure - Le blog d\u00e9co HomeMaison","isPartOf":{"@id":"https:\/\/www.homemaison.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#primaryimage"},"image":{"@id":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#primaryimage"},"thumbnailUrl":"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure.jpg","datePublished":"2015-07-24T12:55:45+00:00","dateModified":"2026-05-28T13:20:34+00:00","description":"HomeMaison propose un service sur mesure pour les rideaux, les voilages et les tringles : mati\u00e8re, dimensions, finition - HomeMaison","breadcrumb":{"@id":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#primaryimage","url":"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure.jpg","contentUrl":"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2015\/07\/rideau-sur-mesure.jpg","width":800,"height":400,"caption":"rideau sur mesure voilage sur mesure"},{"@type":"BreadcrumbList","@id":"https:\/\/www.homemaison.com\/blog\/home-maison-le-sur-mesure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Tous nos articles","item":"https:\/\/www.homemaison.com\/blog\/category\/tous-nos-articles\/"},{"@type":"ListItem","position":2,"name":"Home Maison &#038; le sur-mesure"}]},{"@type":"WebSite","@id":"https:\/\/www.homemaison.com\/blog\/#website","url":"https:\/\/www.homemaison.com\/blog\/","name":"Le blog d\u00e9co HomeMaison","description":"Un blog qui se veut inspirant","publisher":{"@id":"https:\/\/www.homemaison.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.homemaison.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.homemaison.com\/blog\/#organization","name":"Home Maison","url":"https:\/\/www.homemaison.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.homemaison.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2021\/03\/cropped-blog-logo-HM-1.png","contentUrl":"https:\/\/www.homemaison.com\/blog\/wp-content\/uploads\/2021\/03\/cropped-blog-logo-HM-1.png","width":400,"height":138,"caption":"Home Maison"},"image":{"@id":"https:\/\/www.homemaison.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/homemaison","https:\/\/x.com\/homemaison","https:\/\/www.instagram.com\/homemaison\/","https:\/\/fr.pinterest.com\/homemaison\/"]},{"@type":"Person","@id":"https:\/\/www.homemaison.com\/blog\/#\/schema\/person\/95d44530486a00dc07b82cadbf7bb295","name":"Home Maison","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.homemaison.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3e8f4e2a391b3c2f7cef6f6a9c683bb1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e8f4e2a391b3c2f7cef6f6a9c683bb1?s=96&d=mm&r=g","caption":"Home Maison"}}]}},"_links":{"self":[{"href":"https:\/\/www.homemaison.com\/blog\/wp-json\/wp\/v2\/posts\/1579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.homemaison.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.homemaison.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.homemaison.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.homemaison.com\/blog\/wp-json\/wp\/v2\/comments?post=1579"}],"version-history":[{"count":7,"href":"https:\/\/www.homemaison.com\/blog\/wp-json\/wp\/v2\/posts\/1579\/revisions"}],"predecessor-version":[{"id":8063,"href":"https:\/\/www.homemaison.com\/blog\/wp-json\/wp\/v2\/posts\/1579\/revisions\/8063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.homemaison.com\/blog\/wp-json\/wp\/v2\/media\/8064"}],"wp:attachment":[{"href":"https:\/\/www.homemaison.com\/blog\/wp-json\/wp\/v2\/media?parent=1579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.homemaison.com\/blog\/wp-json\/wp\/v2\/categories?post=1579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.homemaison.com\/blog\/wp-json\/wp\/v2\/tags?post=1579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}